{"id":192,"date":"2025-09-16T05:49:47","date_gmt":"2025-09-16T05:49:47","guid":{"rendered":"https:\/\/www.haldren.com\/toulouse\/?page_id=59"},"modified":"2025-11-11T09:06:19","modified_gmt":"2025-11-11T09:06:19","slug":"recherche-de-cadres","status":"publish","type":"page","link":"https:\/\/www.haldren.com\/toulouse\/fr\/acquisition-de-talents\/recherche-de-cadres\/","title":{"rendered":"Recherche de cadres"},"content":{"rendered":"\n  <link rel=\"preload\" as=\"image\" href=\"https:\/\/www.haldren.com\/toulouse\/wp-content\/uploads\/sites\/32\/2025\/09\/toulouse-city.webp\" fetchpriority=\"high\">\n  <style>\n    .inner-banner-section {\n      background-image: url('https:\/\/www.haldren.com\/toulouse\/wp-content\/uploads\/sites\/32\/2025\/09\/toulouse-city.webp');\n      background-size: cover;\n      background-position: center;\n      background-repeat: no-repeat;\n    }\n\n    @media (max-width: 768px) {\n      .inner-banner-section {\n        background-image: url('https:\/\/www.haldren.com\/toulouse\/wp-content\/uploads\/sites\/32\/2025\/09\/toulouse-city.webp');\n      }\n    }\n  <\/style>\n\n<div class=\"block-section inner-banner-section lazyload bg-sty section-gaps top-border-line\">\n  <div class=\"container-fluid\">\n    <div class=\"content-wrap\">\n      <h1 class=\"title\">\n        Services de recherche de cadres \u00e0 Toulouse      <\/h1>\n      <span style=\"font-size: 18px;\">Des solutions expertes en mati\u00e8re de recrutement de cadres pour les entreprises de la ville rose et d&#8217;ailleurs<\/span>\n    <\/div>\n  <\/div>\n<\/div>\n\n\n\n\n<div class=\"wp-block-custom-div-wrapper-block col-wrapper has-sidebar\"><div class=\"content-wrapper\" style=\"background-color:#002a26\">\n<div class=\"block-section section-gaps default-content-section \" \n     style=\"--text-color: #ffffff; --bg-color: #119084;\">\n    <div class=\"container\">\n        <div class=\"default-single-content-wrap\">\n            <div class=\"content-wrap\">\n                                    <h2 data-pm-slice=\"1 1 []\">Un service de recherche de cadres de haut niveau \u00e0 Toulouse<\/h2>\n<p><span data-color=\"transparent\">Haldren propose des services de recherche de cadres de confiance \u00e0 Toulouse, offrant pr\u00e9cision, \u00e9thique et partenariat \u00e0 chaque \u00e9tape du processus de recrutement. <\/span>Nos consultants ont une connaissance approfondie du march\u00e9 de l&#8217;emploi toulousain, ainsi que des ann\u00e9es d&#8217;exp\u00e9rience dans l&#8217;accompagnement des <span data-color=\"transparent\">organisations qui cherchent \u00e0 identifier et \u00e0 s\u00e9curiser les talents les plus qualifi\u00e9s pour des postes de direction<\/span>. <span data-color=\"transparent\">Chaque engagement est d\u00e9fini par la confidentialit\u00e9, la transparence et un engagement in\u00e9branlable \u00e0 fournir des r\u00e9sultats mesurables.<\/span><\/p>\n<p>Notre agence de recrutement travaille en partenariat avec des entreprises de tous secteurs, s&#8217;assurant que chaque nouveau dirigeant renforce leur \u00e9quipe et fait progresser les objectifs de l&#8217;entreprise. Nous savons que la meilleure strat\u00e9gie de recherche de cadres \u00e9quilibre l&#8217;expertise locale et la port\u00e9e internationale, et nos consultants fournissent les deux gr\u00e2ce \u00e0 une m\u00e9thodologie \u00e9prouv\u00e9e et une collaboration significative.<\/p>\n<blockquote><p><strong>Ce qui diff\u00e9rencie Haldren, c&#8217;est notre approche consultative, notre expertise technique et notre engagement in\u00e9branlable \u00e0 trouver les bons talents qui feront toute la diff\u00e9rence pour le succ\u00e8s \u00e0 long terme de votre entreprise.<\/strong><\/p><\/blockquote>\n<h2>Cabinet de recrutement de cadres de haut niveau \u00e0 Toulouse<\/h2>\n<p><span data-color=\"transparent\">Nous sommes un cabinet de recrutement d\u00e9di\u00e9 \u00e0 la recherche de cadres qui alimente le succ\u00e8s \u00e0 long terme de l&#8217;entreprise. Notre mission est de mettre en relation les entreprises avec des cadres sup\u00e9rieurs qui apportent clart\u00e9, dynamisme et innovation dans leur r\u00f4le de leader. Chaque consultant de Haldren combine savoir-faire technique, connaissance de la culture et int\u00e9grit\u00e9 professionnelle pour s&#8217;assurer que chaque placement contribue \u00e0 la performance de l&#8217;organisation.<\/span><\/p>\n<h4>L&#8217;\u00e9valuation<\/h4>\n<p>Chaque collaboration commence par une \u00e9valuation structur\u00e9e des priorit\u00e9s commerciales, des besoins en leadership et de la culture d&#8217;entreprise de notre client. Sur la base des r\u00e9sultats de cette \u00e9valuation, nous \u00e9laborons un profil qui r\u00e9sume les comp\u00e9tences techniques, la motivation et la personnalit\u00e9 du candidat id\u00e9al. <span data-color=\"transparent\">Nos consultants vont au-del\u00e0 de l&#8217;exp\u00e9rience et identifient les professionnels dont l&#8217;\u00e9thique de travail et le style de leadership s&#8217;alignent sur la vision de l&#8217;organisation.<\/span><\/p>\n<h4>Acquisition de talents<\/h4>\n<p>Gr\u00e2ce \u00e0 notre vaste r\u00e9seau et \u00e0 notre approche directe, nous pouvons identifier les candidats ad\u00e9quats dans diff\u00e9rents pays et secteurs. Nous utilisons une combinaison de m\u00e9thodes de recrutement traditionnelles et de sourcing num\u00e9rique innovant pour entrer en contact avec des candidats qui sont activement \u00e0 la recherche de nouveaux postes et d&#8217;autres qui ne le sont pas. <span data-color=\"transparent\">Notre objectif est de trouver des leaders capables de diriger des \u00e9quipes complexes et de guider les entreprises sur le march\u00e9 toulousain en pleine \u00e9volution.<\/span><\/p>\n<h4>Transformation organisationnelle<\/h4>\n<p>Notre soutien ne s&#8217;arr\u00eate pas \u00e0 l&#8217;embauche. Nous offrons \u00e9galement une assistance en mati\u00e8re de d\u00e9veloppement du leadership, de planification de la succession, de gestion des talents et d&#8217;autres fonctions RH. En d&#8217;autres termes, Haldren aide ses clients \u00e0 renforcer les syst\u00e8mes qui favorisent la croissance et \u00e0 retenir les meilleurs talents, dans le but de devenir un partenaire de confiance tout au long du processus de recrutement de chaque client.<\/p>\n<h2>Notre approche de la recherche de cadres<\/h2>\n<p><span data-color=\"transparent\">Notre approche de la recherche de cadres refl\u00e8te notre conviction que chaque placement est une d\u00e9cision strat\u00e9gique. Nous commen\u00e7ons chaque mission par une session de d\u00e9couverte afin de conna\u00eetre les d\u00e9fis, la culture et les attentes de l&#8217;entreprise \u00e0 l&#8217;\u00e9gard des candidats. La compr\u00e9hension de ces dynamiques nous permet d&#8217;aligner le processus de recherche sur les besoins de recrutement de l&#8217;entreprise. <\/span><\/p>\n<p><span data-color=\"transparent\">Ensuite, nous \u00e9laborons un profil de candidat d\u00e9taill\u00e9 qui d\u00e9finit les qualifications requises, les comp\u00e9tences en mati\u00e8re de leadership et les comp\u00e9tences techniques du poste. Nous dressons ensuite une carte du march\u00e9 de l&#8217;emploi afin d&#8217;identifier les candidats potentiels qui r\u00e9pondent \u00e0 ces crit\u00e8res ou les d\u00e9passent. Nous \u00e9valuons les candidats potentiels \u00e0 l&#8217;aide de tests psychom\u00e9triques, d&#8217;entretiens structur\u00e9s et de v\u00e9rifications des r\u00e9f\u00e9rences, en veillant \u00e0 ce que les personnes pr\u00e9s\u00e9lectionn\u00e9es fassent preuve non seulement de capacit\u00e9s mais aussi de caract\u00e8re.<\/span><\/p>\n<p>Nos consultants combinent leur connaissance du march\u00e9 local toulousain avec l&#8217;envergure mondiale de Haldren pour trouver les professionnels ad\u00e9quats pour les postes cl\u00e9s. Ils utilisent \u00e9galement les plateformes sociales, les r\u00e9seaux professionnels et les offres d&#8217;emploi cibl\u00e9es. <span data-color=\"transparent\">Cette double approche nous permet de trouver des leaders qui r\u00e9pondent aux crit\u00e8res d&#8217;embauche et s&#8217;alignent sur la culture d&#8217;entreprise de nos clients.<\/span><\/p>\n<p>Chaque d\u00e9cision que nous prenons est \u00e9tay\u00e9e par des donn\u00e9es. <span data-color=\"transparent\">Nous utilisons l&#8217;analyse pour suivre l&#8217;efficacit\u00e9 du sourcing, l&#8217;engagement des candidats et les placements r\u00e9ussis au fil du temps. Ces mesures renforcent l&#8217;apprentissage continu au sein de notre \u00e9quipe, ce qui nous permet d&#8217;affiner nos m\u00e9thodes et de maintenir notre position en tant qu&#8217;agence de recrutement leader \u00e0 Toulouse.<\/span><\/p>\n<p><span data-color=\"transparent\">Notre processus met l&#8217;accent sur la transparence et la collaboration. Nous communiquons r\u00e9guli\u00e8rement avec nos clients et adaptons les strat\u00e9gies de recherche en fonction des besoins afin de garantir un alignement optimal. Compar\u00e9 au recrutement g\u00e9n\u00e9ral, notre mod\u00e8le structur\u00e9 et consultatif permet d&#8217;obtenir des taux de r\u00e9tention plus \u00e9lev\u00e9s et des r\u00e9sultats plus solides en mati\u00e8re de leadership. C&#8217;est une m\u00e9thodologie fond\u00e9e sur la confiance, l&#8217;\u00e9thique et des r\u00e9sultats mesurables.<\/span><\/p>\n<h2>Notre expertise en tant que leader du recrutement de cadres \u00e0 Toulouse<\/h2>\n<p>Les consultants de Haldren allient une connaissance sp\u00e9cialis\u00e9e de l&#8217;industrie \u00e0 une compr\u00e9hension pratique de l&#8217;\u00e9conomie toulousaine. Cela nous permet de servir des entreprises couvrant les secteurs de l&#8217;a\u00e9rospatiale, de la finance, de l&#8217;\u00e9nergie verte, de la technologie, de la sant\u00e9 et de l&#8217;immobilier, entre autres, et de nous adapter \u00e0 l&#8217;\u00e9volution des tendances et des r\u00e9glementations du march\u00e9.<\/p>\n<p>Notre \u00e9quipe s&#8217;engage \u00e9galement dans une formation continue pour rester \u00e0 la pointe de l&#8217;\u00e9volution de la l\u00e9gislation du travail et des normes de recrutement. De nombreux consultants de Haldren ont eux-m\u00eames occup\u00e9 des postes de direction, ce qui leur permet de conseiller les clients sur les r\u00f4les de leadership et la n\u00e9gociation des salaires. Ils fournissent des conseils fond\u00e9s \u00e0 la fois sur une expertise du monde r\u00e9el et sur des connaissances techniques.<\/p>\n<p>Nous pensons qu&#8217;un retour d&#8217;information constant, l&#8217;adaptabilit\u00e9 et l&#8217;\u00e9coute font toute la diff\u00e9rence dans l&#8217;obtention de r\u00e9sultats durables. Ces qualit\u00e9s, associ\u00e9es \u00e0 l&#8217;engagement ind\u00e9fectible de Haldren en faveur de l&#8217;int\u00e9grit\u00e9 et du partenariat, sont ce que les clients appr\u00e9cient le plus dans leur collaboration avec nous.<\/p>\n<h4>Quelques domaines dans lesquels nous sommes sp\u00e9cialis\u00e9s<\/h4>\n<p>Notre agence de recrutement \u00e0 Toulouse soutient des entreprises op\u00e9rant dans diff\u00e9rents secteurs d&#8217;activit\u00e9 \u00e0 travers la France et l&#8217;Europe. Les secteurs pour lesquels nous recrutons r\u00e9guli\u00e8rement incluent, sans s&#8217;y limiter, l&#8217;\u00e9nergie verte, la sant\u00e9, la fabrication, l&#8217;a\u00e9rospatiale, la technologie et les biens de consommation. Chaque engagement est collaboratif, strat\u00e9gique et enti\u00e8rement align\u00e9 sur les objectifs de nos clients.<\/p>\n<h4>Exemples de postes pour lesquels nous recrutons<\/h4>\n<p>Nous proposons des services de recrutement pour des postes de direction et de haut niveau, tels que directeur financier, directeur des ventes, directeur g\u00e9n\u00e9ral et directeur des ressources humaines. Nos consultants aident \u00e9galement les professionnels en devenir qui sont pr\u00eats \u00e0 progresser dans leur carri\u00e8re vers le leadership. <span data-color=\"transparent\">Que les clients se d\u00e9veloppent sur de nouveaux march\u00e9s ou qu&#8217;ils restructurent leurs \u00e9quipes de direction, nous les aidons \u00e0 trouver des leaders qui inspirent le progr\u00e8s. <\/span><\/p>\n<blockquote><p><strong>Pour d\u00e9couvrir les postes de direction pour lesquels nous recrutons ou pour discuter des besoins de votre organisation en mati\u00e8re de recrutement, contactez Haldren d\u00e8s aujourd&#8217;hui. Notre \u00e9quipe sera ravie de vous aider \u00e0 trouver la bonne personne.<\/strong><\/p><\/blockquote>\n<h2>Pourquoi Haldren utilise une approche personnalis\u00e9e du recrutement<\/h2>\n<p>Les pratiques de recrutement g\u00e9n\u00e9riques permettent rarement d&#8217;obtenir des r\u00e9sultats durables. Nos consultants ont constat\u00e9 de premi\u00e8re main que les m\u00e9thodes uniformes n\u00e9gligent des \u00e9l\u00e9ments essentiels tels que la culture d&#8217;entreprise, les styles de leadership et les exigences techniques. Au fil des ann\u00e9es pass\u00e9es \u00e0 soutenir des entreprises locales et internationales, nous avons confirm\u00e9 que les strat\u00e9gies de recherche personnalis\u00e9es offrent syst\u00e9matiquement les meilleurs r\u00e9sultats, tant pour les employeurs que pour les demandeurs d&#8217;emploi.<\/p>\n<p>Plusieurs de nos consultants se souviennent d&#8217;avoir conseill\u00e9 un client dont l&#8217;expansion rapide n\u00e9cessitait des embauches imm\u00e9diates. Au lieu de pr\u00e9cipiter le processus d&#8217;embauche, nous avons affin\u00e9 les param\u00e8tres et le calendrier de la recherche. Cela a conduit \u00e0 des placements r\u00e9ussis qui ont am\u00e9lior\u00e9 la r\u00e9tention et la performance. <span data-color=\"transparent\">Nous appliquons cette m\u00eame discipline \u00e0 chaque projet, en veillant \u00e0 ce que chaque processus de recrutement refl\u00e8te le contexte, le march\u00e9 et les attentes du client.<\/span><\/p>\n<p>Notre processus donne \u00e9galement la priorit\u00e9 \u00e0 l&#8217;exp\u00e9rience du candidat. Nous fournissons des commentaires et des conseils r\u00e9fl\u00e9chis aux demandeurs d&#8217;emploi, les aidant \u00e0 faire des choix \u00e9clair\u00e9s dans leur recherche d&#8217;emploi et veillant \u00e0 ce que les deux parties de la relation d&#8217;embauche se sentent respect\u00e9es et inform\u00e9es. <span data-color=\"transparent\">Cela renforce notre r\u00e9putation d&#8217;agence de recrutement de premier plan qui accorde une grande importance \u00e0 la transparence et \u00e0 l&#8217;\u00e9thique.<\/span><\/p>\n<h2>Pourquoi choisir Haldren pour la recherche de cadres ?<\/h2>\n<p><span data-color=\"transparent\">Le choix du bon partenaire de recrutement d\u00e9termine la qualit\u00e9 de votre \u00e9quipe de direction. <\/span>La r\u00e9putation de Haldren <span data-color=\"transparent\">repose sur la confidentialit\u00e9, la pr\u00e9cision et la constance de ses prestations<\/span>. Nos clients nous font confiance car nous prot\u00e9geons leur vie priv\u00e9e et nous nous assurons que chaque processus de recrutement est trait\u00e9 avec professionnalisme et discr\u00e9tion.<\/p>\n<p>Nous avons cultiv\u00e9 un vaste r\u00e9seau de cadres sup\u00e9rieurs et de sp\u00e9cialistes de l&#8217;industrie dans la r\u00e9gion de Toulouse et au-del\u00e0. Ce r\u00e9seau nous permet de mettre en relation les entreprises avec les meilleurs candidats qui apportent de la valeur et de la stabilit\u00e9 aux structures de direction. Notre m\u00e9thodologie \u00e9prouv\u00e9e, compos\u00e9e d&#8217;entretiens structur\u00e9s, de v\u00e9rifications des r\u00e9f\u00e9rences et d&#8217;une \u00e9valuation collaborative, permet aux entreprises de prendre des d\u00e9cisions de recrutement plus inform\u00e9es et plus s\u00fbres.<\/p>\n<p>Nous pensons que l&#8217;\u00e9quit\u00e9, la transparence et la fiabilit\u00e9 ne sont pas n\u00e9gociables, et nous mesurons notre succ\u00e8s par la force et la long\u00e9vit\u00e9 des relations que nous entretenons avec nos clients. Nos clients nous consid\u00e8rent comme des partenaires qui les aident \u00e0 recruter les meilleurs talents, \u00e0 renforcer la culture et \u00e0 obtenir des r\u00e9sultats durables.<\/p>\n<p><span data-color=\"transparent\">Lorsque vous travaillez avec Haldren, vous b\u00e9n\u00e9ficiez d&#8217;un partenaire de confiance qui s&#8217;engage \u00e0 trouver des leaders capables d&#8217;\u00e9lever votre entreprise.<\/span><\/p>\n<blockquote><p><strong><span data-color=\"transparent\">Si votre organisation est pr\u00eate \u00e0 faire appel \u00e0 un partenaire professionnel et \u00e9thique pour le recrutement de cadres, contactez Haldren d\u00e8s aujourd&#8217;hui <\/span><\/strong><\/p><\/blockquote>\n<p>. <\/p>\n                            <\/div>\n        <\/div>\n    <\/div>\n<\/div>\n\n<div class=\"block-section accordion-main-section \">\n    <div class=\"container\">    \n                <div class=\"accordion-faqs\">\n            <h2 class=\"m-title\">Frequently Asked Questions (FAQs)<\/h2>\n                        <div class=\"item\">\n                <h3>Comment commencer \u00e0 travailler avec Haldren sur une recherche de cadres ?<\/h3>\n                <div class=\"faq-content\"><p data-pm-slice=\"1 1 []\">Nous commen\u00e7ons chaque partenariat par une r\u00e9union de d\u00e9couverte afin de comprendre les objectifs de votre entreprise, la structure de votre \u00e9quipe et vos besoins en mati\u00e8re de leadership. Une fois que nous nous sommes mis d&#8217;accord sur le champ d&#8217;application, nos consultants commencent \u00e0 cartographier le march\u00e9 et \u00e0 identifier les candidats potentiels qui correspondent \u00e0 vos valeurs et \u00e0 vos objectifs.<\/p>\n<\/div>\n            <\/div>\n                        <div class=\"item\">\n                <h3>Qu&#039;est-ce qui diff\u00e9rencie Haldren des autres cabinets de recrutement ?<\/h3>\n                <div class=\"faq-content\"><p data-pm-slice=\"1 1 []\">Nos consultants adoptent une approche consultative ax\u00e9e sur l&#8217;\u00e9thique, les r\u00e9sultats \u00e0 long terme et les r\u00e9sultats mesurables. Au lieu de s&#8217;appuyer sur des listes g\u00e9n\u00e9riques ou des algorithmes, nous construisons chaque recherche \u00e0 partir de la base, en veillant \u00e0 ce que chaque recommandation refl\u00e8te une r\u00e9elle perspicacit\u00e9 et une connexion humaine.<\/p>\n<\/div>\n            <\/div>\n                        <div class=\"item\">\n                <h3>Que se passe-t-il si nous ne trouvons pas imm\u00e9diatement le bon candidat ?<\/h3>\n                <div class=\"faq-content\"><p data-pm-slice=\"1 1 []\">Si la premi\u00e8re liste n&#8217;est pas parfaite, nous affinons notre strat\u00e9gie. Nos consultants r\u00e9\u00e9valuent le cahier des charges, \u00e9largissent le champ de la recherche et continuent jusqu&#8217;\u00e0 ce que nous ayons identifi\u00e9 les candidats qui r\u00e9pondent vraiment \u00e0 vos attentes. Nous sommes convaincus que la pers\u00e9v\u00e9rance et le partenariat conduisent aux meilleurs r\u00e9sultats.<\/p>\n<\/div>\n            <\/div>\n                        <div class=\"item\">\n                <h3>Haldren peut-il nous aider \u00e0 recruter pour plusieurs postes \u00e0 la fois ?<\/h3>\n                <div class=\"faq-content\"><p data-pm-slice=\"1 1 []\">Oui. Nous soutenons souvent des clients qui se d\u00e9veloppent rapidement ou qui restructurent leurs \u00e9quipes de direction. Nos consultants con\u00e7oivent des plans de recherche coordonn\u00e9s qui garantissent la coh\u00e9rence des valeurs, de la communication et de l&#8217;exp\u00e9rience des candidats pour plusieurs fonctions.<\/p>\n<\/div>\n            <\/div>\n                    <\/div>\n            <\/div>\n<\/div><\/div><div class=\"sidebar-wrapper\">\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f49-o1\" lang=\"\" dir=\"ltr\" data-wpcf7-id=\"49\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/toulouse\/wp-json\/wp\/v2\/pages\/192#wpcf7-f49-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Contact form\" enctype=\"multipart\/form-data\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"49\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.5\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f49-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/fieldset>\n<input class=\"wpcf7-form-control wpcf7-hidden\" id=\"utm_source\" value=\"\" type=\"hidden\" name=\"utm_source\" \/>\n<input class=\"wpcf7-form-control wpcf7-hidden\" id=\"utm_medium\" value=\"\" type=\"hidden\" name=\"utm_medium\" \/>\n<input class=\"wpcf7-form-control wpcf7-hidden\" id=\"sideform_user_country\" value=\"\" type=\"hidden\" name=\"userCountry\" \/>\n<div class=\"form-grid-layout\">\n\t<div class=\"form-title\">\n\t\t<h2 class=\"title\">Thrive with Top Talent<br \/>\n- No Upfronts Fees\n\t\t<\/h2>\n\t\t<p>Have it easier with video interview clips and a candidate shortlist within 2-3 weeks\n\t\t<\/p>\n\t<\/div>\n\t<div class=\"input-field\">\n\t\t<p><label for=\"\">Name<\/label><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"full-Name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"full-Name\" \/><\/span>\n\t\t<\/p>\n\t<\/div>\n\t<div class=\"input-field\">\n\t\t<p><label for=\"\">Email Address<\/label><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"email-address\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"email\" name=\"email-address\" \/><\/span>\n\t\t<\/p>\n\t<\/div>\n\t<div class=\"input-field\">\n\t\t<p><label for=\"\">Company<\/label><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"company\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"company\" \/><\/span>\n\t\t<\/p>\n\t<\/div>\n\t<div class=\"radiobox-field\">\n\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"radio-721company-status\"><span class=\"wpcf7-form-control wpcf7-radio\"><span class=\"wpcf7-list-item first\"><label><input type=\"radio\" name=\"radio-721company-status\" value=\"{Employer}\" \/><span class=\"wpcf7-list-item-label\">Employer<\/span><\/label><\/span><span class=\"wpcf7-list-item last\"><label><input type=\"radio\" name=\"radio-721company-status\" value=\"{Candidate}\" \/><span class=\"wpcf7-list-item-label\">Candidate<\/span><\/label><\/span><\/span><\/span>\n\t\t<\/p>\n\t<\/div>\n\t<div class=\"input-field\">\n\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"file-upload\"><input size=\"40\" class=\"wpcf7-form-control wpcf7-file\" accept=\".pdf\" aria-invalid=\"false\" type=\"file\" name=\"file-upload\" \/><\/span>\n\t\t<\/p>\n\t<\/div>\n\t<div class=\"textarea-field\">\n\t\t<p><label for=\"\">How can we help you?<\/label><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"message\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\" name=\"message\"><\/textarea><\/span>\n\t\t<\/p>\n\t<\/div>\n\t<p><span id=\"wpcf7-6a04716d25edd-wrapper\" class=\"wpcf7-form-control-wrap nickname-wrap\" ><input id=\"wpcf7-6a04716d25edd-field\"  class=\"wpcf7-form-control wpcf7-text\" type=\"text\" name=\"nickname\" value=\"\" size=\"40\" tabindex=\"-1\" autocomplete=\"off\" \/><\/span>\n\t<\/p>\n\t<div class=\"form-term\">\n\t\t<p>Submission of this form means you have agreed to our <a href=\"\/privacy-policy\/\" title=\"\">Privacy Policy<\/a> and <a href=\"\/terms-of-service\/\" title=\"\">Terms Conditions<\/a>\n\t\t<\/p>\n\t<\/div>\n\t<div class=\"submit-btn\">\n\t\t<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner btn-box\" type=\"submit\" value=\"Get in Touch\" \/>\n\t\t<\/p>\n\t<\/div>\n<\/div><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n<\/div><\/div>\n\n\n<div class=\"block-section client-reviews-slider \" style=\"background-color: #119084\">  \n    <div class=\"container\">\n                <div class=\"splide client-slider\">\n            <div class=\"splide__track\">\n                <div class=\"splide__list\">\n                                        <div class=\"splide__slide\">\n                        <div class=\"content-box\">\n                            <div class=\"content\">\n                                <p data-pm-slice=\"1 1 []\">&#8220;Notre exp\u00e9rience avec Haldren a \u00e9t\u00e9 tr\u00e8s enrichissante. Nous ne nous sommes jamais sentis bouscul\u00e9s ou mis sous pression, mais simplement guid\u00e9s par une \u00e9quipe qui avait vraiment \u00e0 c\u0153ur de trouver les bonnes personnes pour notre organisation.&#8221;<\/p>\n                            <\/div>\n                                                        <div class=\"name\">\n                                <strong>Sophie R.<\/strong>, \n                                Coordinateur du recrutement                            <\/div>\n                                                    <\/div>\n                    <\/div>\n                                        <div class=\"splide__slide\">\n                        <div class=\"content-box\">\n                            <div class=\"content\">\n                                <p data-pm-slice=\"1 1 []\">&#8220;Nous avons appr\u00e9ci\u00e9 la transparence et la facilit\u00e9 de contact de l&#8217;\u00e9quipe Haldren. Ils ont pos\u00e9 des questions r\u00e9fl\u00e9chies et ont donn\u00e9 un retour d&#8217;information honn\u00eate. Nous avons vraiment eu l&#8217;impression d&#8217;un partenariat fond\u00e9 sur la confiance&#8221;.<\/p>\n                            <\/div>\n                                                        <div class=\"name\">\n                                <strong>Fabienne L.<\/strong>, \n                                Directeur g\u00e9n\u00e9ral                            <\/div>\n                                                    <\/div>\n                    <\/div>\n                                        <div class=\"splide__slide\">\n                        <div class=\"content-box\">\n                            <div class=\"content\">\n                                <p data-pm-slice=\"1 1 []\">&#8220;Nous nous sommes adress\u00e9s \u00e0 Haldren avec un cahier des charges difficile, et ils l&#8217;ont g\u00e9r\u00e9 avec une expertise sereine. Leurs consultants sont rest\u00e9s en contact avec nous, nous ont communiqu\u00e9 r\u00e9guli\u00e8rement des mises \u00e0 jour et ont fait en sorte que l&#8217;ensemble du processus se d\u00e9roule sans probl\u00e8me du d\u00e9but \u00e0 la fin.<\/p>\n                            <\/div>\n                                                        <div class=\"name\">\n                                <strong>Ignace B.<\/strong>, \n                                Directeur des ressources humaines                            <\/div>\n                                                    <\/div>\n                    <\/div>\n                                    <\/div>\n            <\/div>\n        <\/div>\n            <\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"author":10,"featured_media":0,"parent":188,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-192","page","type-page","status-publish","hentry"],"acf":[],"lang":"fr","translations":{"fr":192,"en":59},"jetpack_sharing_enabled":true,"pll_sync_post":[],"_links":{"self":[{"href":"https:\/\/www.haldren.com\/toulouse\/wp-json\/wp\/v2\/pages\/192","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.haldren.com\/toulouse\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.haldren.com\/toulouse\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.haldren.com\/toulouse\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.haldren.com\/toulouse\/wp-json\/wp\/v2\/comments?post=192"}],"version-history":[{"count":1,"href":"https:\/\/www.haldren.com\/toulouse\/wp-json\/wp\/v2\/pages\/192\/revisions"}],"predecessor-version":[{"id":207,"href":"https:\/\/www.haldren.com\/toulouse\/wp-json\/wp\/v2\/pages\/192\/revisions\/207"}],"up":[{"embeddable":true,"href":"https:\/\/www.haldren.com\/toulouse\/wp-json\/wp\/v2\/pages\/188"}],"wp:attachment":[{"href":"https:\/\/www.haldren.com\/toulouse\/wp-json\/wp\/v2\/media?parent=192"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}